{"id":87,"count":1,"description":"","link":"https:\/\/allamdesigner.com\/en\/category\/design-trends\/","name":"Design trends","slug":"design-trends","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/allamdesigner.com\/en\/wp-json\/wp\/v2\/categories\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allamdesigner.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/allamdesigner.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/allamdesigner.com\/en\/wp-json\/wp\/v2\/posts?categories=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}